{"id":3443,"date":"2025-04-18T15:01:49","date_gmt":"2025-04-18T13:01:49","guid":{"rendered":"http:\/\/sacto.it\/prodotto\/watertight-copper-rivet-4-8x9\/"},"modified":"2025-04-18T15:01:49","modified_gmt":"2025-04-18T13:01:49","slug":"watertight-copper-rivet-4-8x9","status":"publish","type":"product","link":"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/","title":{"rendered":"WATERTIGHT COPPER RIVET 4.8X9"},"content":{"rendered":"<p>Watertight rivets made of copper nail galvanized steel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Watertight rivets made of copper nail galvanized steel<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"listino_tag":[],"product_brand":[],"product_cat":[2340],"product_tag":[2362,2324,2314],"class_list":["post-3443","product","type-product","status-publish","product_cat-blind-rivet-production","product_tag-list-100","product_tag-listino-9-en","product_tag-price-list-004","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WATERTIGHT COPPER RIVET 4.8X9 - Sistemi di Fissaggio per l&#039;Industria | SACTO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WATERTIGHT COPPER RIVET 4.8X9 - Sistemi di Fissaggio per l&#039;Industria | SACTO\" \/>\n<meta property=\"og:description\" content=\"Watertight rivets made of copper nail galvanized steel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/\" \/>\n<meta property=\"og:site_name\" content=\"Sistemi di Fissaggio per l&#039;Industria | SACTO\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sacto.it\/wp-content\/uploads\/2025\/02\/sacto-social-share.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/\",\"url\":\"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/\",\"name\":\"WATERTIGHT COPPER RIVET 4.8X9 - Sistemi di Fissaggio per l&#039;Industria | SACTO\",\"isPartOf\":{\"@id\":\"https:\/\/sacto.it\/en\/#website\"},\"datePublished\":\"2025-04-18T13:01:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sacto.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/sacto.it\/en\/produzione-sistemi-fissaggio-industriali\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blind rivets\",\"item\":\"https:\/\/sacto.it\/en\/product-category\/blind-rivet-production\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Watertight rivets made of copper nail galvanized steel\",\"item\":\"http:\/\/sacto.it\/en\/product\/watertight-rivets-made-of-copper-nail-galvanized-steel\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"WATERTIGHT COPPER RIVET 4.8X9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sacto.it\/en\/#website\",\"url\":\"https:\/\/sacto.it\/en\/\",\"name\":\"Sistemi di Fissaggio per l'Industria | SACTO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sacto.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sacto.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sacto.it\/en\/#organization\",\"name\":\"Sistemi di Fissaggio per l'Industria | SACTO\",\"url\":\"https:\/\/sacto.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sacto.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/sacto.it\/wp-content\/uploads\/2025\/02\/logo-sacto.png\",\"contentUrl\":\"http:\/\/sacto.it\/wp-content\/uploads\/2025\/02\/logo-sacto.png\",\"width\":399,\"height\":82,\"caption\":\"Sistemi di Fissaggio per l'Industria | SACTO\"},\"image\":{\"@id\":\"https:\/\/sacto.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WATERTIGHT COPPER RIVET 4.8X9 - Sistemi di Fissaggio per l&#039;Industria | SACTO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/","og_locale":"en_US","og_type":"article","og_title":"WATERTIGHT COPPER RIVET 4.8X9 - Sistemi di Fissaggio per l&#039;Industria | SACTO","og_description":"Watertight rivets made of copper nail galvanized steel","og_url":"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/","og_site_name":"Sistemi di Fissaggio per l&#039;Industria | SACTO","og_image":[{"width":1200,"height":675,"url":"https:\/\/sacto.it\/wp-content\/uploads\/2025\/02\/sacto-social-share.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/","url":"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/","name":"WATERTIGHT COPPER RIVET 4.8X9 - Sistemi di Fissaggio per l&#039;Industria | SACTO","isPartOf":{"@id":"https:\/\/sacto.it\/en\/#website"},"datePublished":"2025-04-18T13:01:49+00:00","breadcrumb":{"@id":"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sacto.it\/en\/product\/watertight-copper-rivet-4-8x9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sacto.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/sacto.it\/en\/produzione-sistemi-fissaggio-industriali\/"},{"@type":"ListItem","position":3,"name":"Blind rivets","item":"https:\/\/sacto.it\/en\/product-category\/blind-rivet-production\/"},{"@type":"ListItem","position":4,"name":"Watertight rivets made of copper nail galvanized steel","item":"http:\/\/sacto.it\/en\/product\/watertight-rivets-made-of-copper-nail-galvanized-steel\/"},{"@type":"ListItem","position":5,"name":"WATERTIGHT COPPER RIVET 4.8X9"}]},{"@type":"WebSite","@id":"https:\/\/sacto.it\/en\/#website","url":"https:\/\/sacto.it\/en\/","name":"Sistemi di Fissaggio per l'Industria | SACTO","description":"","publisher":{"@id":"https:\/\/sacto.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sacto.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sacto.it\/en\/#organization","name":"Sistemi di Fissaggio per l'Industria | SACTO","url":"https:\/\/sacto.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sacto.it\/en\/#\/schema\/logo\/image\/","url":"http:\/\/sacto.it\/wp-content\/uploads\/2025\/02\/logo-sacto.png","contentUrl":"http:\/\/sacto.it\/wp-content\/uploads\/2025\/02\/logo-sacto.png","width":399,"height":82,"caption":"Sistemi di Fissaggio per l'Industria | SACTO"},"image":{"@id":"https:\/\/sacto.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/product\/3443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/media?parent=3443"}],"wp:term":[{"taxonomy":"listino_tag","embeddable":true,"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/listino_tag?post=3443"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/product_brand?post=3443"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/product_cat?post=3443"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sacto.it\/en\/wp-json\/wp\/v2\/product_tag?post=3443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}